{"id":5230,"date":"2025-04-03T14:22:44","date_gmt":"2025-04-03T12:22:44","guid":{"rendered":"https:\/\/panots.es\/quienes-somos\/"},"modified":"2025-10-14T17:32:58","modified_gmt":"2025-10-14T15:32:58","slug":"qui-som","status":"publish","type":"page","link":"https:\/\/panots.es\/ca\/qui-som\/","title":{"rendered":"Qui som"},"content":{"rendered":"\r\n    <div  class=\"block-mainslider alignfull\">\r\n        <div class=\"js-mainslider swiper relative\" data-count=\"1\" data-nav=\"none\" data-autoplay=\"0\">\r\n            <ul class=\"mainslider swiper-wrapper m-0 list-none\">\r\n                \r\n<li class=\"mainslider__item swiper-slide aspect-2\/3 md:aspect-21\/9\">\r\n    <div class=\"container mainslider__content relative z-10 h-full text-white flex flex-col gap-1 items-center justify-center\">\r\n\r\n        \r\n                            <\/div>\r\n\r\n    \r\n            <picture>\r\n            <source media=\"(max-width: 600px)\" srcset=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/gemini-image-2_Place_the_headline_SALE_SEASON_and_the_subtitle_LIMITED_UNITS_signif-0-scaled.jpg\">\r\n            <source media=\"(min-width: 1024px)\" srcset=\"https:\/\/panots.es\/wp-content\/uploads\/2026\/07\/nano-banana-2_Prompt_para_Leonardo_AI_Use_the_uploaded_sneaker_image_as_the_exact_product_refe-3-scaled.jpg\">\r\n            <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/panots.es\/wp-content\/uploads\/2026\/07\/nano-banana-2_Prompt_para_Leonardo_AI_Use_the_uploaded_sneaker_image_as_the_exact_product_refe-3-scaled.jpg\" class=\"w-full h-full absolute object-cover inset-0 z-0 aspect-21\/9 lazyload\" alt=\"\" loading=\"eager\" fetchpriority=\"high\" title=\"\"><noscript><img decoding=\"async\" src=\"https:\/\/panots.es\/wp-content\/uploads\/2026\/07\/nano-banana-2_Prompt_para_Leonardo_AI_Use_the_uploaded_sneaker_image_as_the_exact_product_refe-3-scaled.jpg\" data-src=\"https:\/\/panots.es\/wp-content\/uploads\/2026\/07\/nano-banana-2_Prompt_para_Leonardo_AI_Use_the_uploaded_sneaker_image_as_the_exact_product_refe-3-scaled.jpg\" class=\"w-full h-full absolute object-cover inset-0 z-0 aspect-21\/9\" alt=\"\" loading=\"eager\" fetchpriority=\"high\" data- title=\"\"><\/noscript>\r\n        <\/picture>\r\n    <\/li>            <\/ul>\r\n            <div class=\"swiper-pagination\"><\/div>\r\n\r\n                    <\/div>\r\n\r\n    <\/div>\r\n\n\n\r\n\r\n<section  class=\"block-text2cols pt-8 md:pt-12 lg:pt-28\"> <!-- section -->\r\n\r\n    <div class=\"grid gap-x-baseGap md:gap-x-14 gap-y-8 lg:grid-cols-2\"> <!-- if is a full width section, apply container -->\r\n\r\n        <!-- Left column -->\r\n\r\n        <div>\r\n            <p class=\"text-primary font-bold text-lg mb-2 lg:max-w-[610px]\">Panots<\/p><h2 class=\"mt-0 mb-3 text-balance max-w-[700px]\">Creem peces que expliquen hist\u00f2ries, acompanyen cada pas i contribueixen al benestar del planeta.<\/h2>        <\/div>\r\n        \r\n        \r\n        <!-- Right column -->\r\n        <div>\r\n            <div class=\"lg:max-w-[610px] text-base\"><p>Panots \u00e9s una marca global de cal\u00e7at que combina disseny contemporani, funcionalitat i responsabilitat social. Inspirada en la connexi\u00f3 entre les persones i les ciutats, el nostre nom ret homenatge a les ic\u00f2niques rajoles que han estat testimonis d&#8217;innombrables hist\u00f2ries. M\u00e9s que sabates, creem peces que expliquen hist\u00f2ries, acompanyen cada pas i contribueixen al benestar del planeta.<\/p>\n<p>Amb una missi\u00f3 clara de promoure la sostenibilitat, Panots no nom\u00e9s dissenya cal\u00e7at, sin\u00f3 que tamb\u00e9 impulsa iniciatives com RENUEVA, un moviment que d\u00f3na nova vida als sabates mitjan\u00e7ant el seu reciclatge i reutilitzaci\u00f3, donant suport a comunitats necessitades. A Panots, cada parell de sabates porta amb si un prop\u00f2sit: unir estil, funcionalitat i un impacte positiu en la societat i el medi ambient.<\/p>\n<\/div>        <\/div>\r\n\r\n\t<\/div>\r\n\r\n<\/section>\n\n\r\n\r\n<section  class=\"features-list py-8 md:py-12 lg:py-28\">\r\n\r\n    <div class=\"\">\r\n\r\n        \r\n                    <ul class=\"list-none m-0 grid gap-baseGap xl:grid-cols-3\">\r\n                                                        <li class=\"w-full max-w-full text-center bg-gray-100 rounded-2xl py-10 px-6 lg:px-10\">\r\n                                                                            <strong class=\"text-xl block mb-2 text-center\">Sostenibilitat<\/strong>\r\n                                                                            <p class=\"mt-0 m-0 text-center mb-5\">Una vegada a l&#8217;any fem una crida per recollir els Panots que ja s&#8217;han utilitzat, per donar-los una nova vida o per donar-los a qui els necessita.<\/p>\r\n                                                \r\n                    <\/li>\r\n                                                        <li class=\"w-full max-w-full text-center bg-gray-100 rounded-2xl py-10 px-6 lg:px-10\">\r\n                                                                            <strong class=\"text-xl block mb-2 text-center\">Qualitat<\/strong>\r\n                                                                            <p class=\"mt-0 m-0 text-center mb-5\">Cal\u00e7at dissenyat amb materials duradors i confortables. La comoditat que ofereix Panots \u00e9s la seva gran diferenciaci\u00f3.<\/p>\r\n                                                \r\n                    <\/li>\r\n                                                        <li class=\"w-full max-w-full text-center bg-gray-100 rounded-2xl py-10 px-6 lg:px-10\">\r\n                                                                            <strong class=\"text-xl block mb-2 text-center\">Innovaci\u00f3<\/strong>\r\n                                                                            <p class=\"mt-0 m-0 text-center mb-5\">Incorporem processos moderns que garanteixen productes \u00fanics al mercat amb dissenyadors asi\u00e0tics, espanyols i llatinoamericans.<\/p>\r\n                                                \r\n                    <\/li>\r\n                                                        <li class=\"w-full max-w-full text-center bg-gray-100 rounded-2xl py-10 px-6 lg:px-10\">\r\n                                                                            <strong class=\"text-xl block mb-2 text-center\">Comprom\u00eds social<\/strong>\r\n                                                                            <p class=\"mt-0 m-0 text-center mb-5\">Treballem per donar suport a comunitats necessitades mitjan\u00e7ant la donaci\u00f3 de cal\u00e7at i pr\u00e0ctiques solid\u00e0ries com Renova i Panobus.<\/p>\r\n                                                \r\n                    <\/li>\r\n                                                        <li class=\"w-full max-w-full text-center bg-gray-100 rounded-2xl py-10 px-6 lg:px-10\">\r\n                                                                            <strong class=\"text-xl block mb-2 text-center\">Postvenda responsable<\/strong>\r\n                                                                            <p class=\"mt-0 m-0 text-center mb-5\">Afegim accessoris que allarguen la seva vida \u00fatil, redueixen l&#8217;impacte ambiental i enforteixen el vincle amb els nostres clients.<\/p>\r\n                                                \r\n                    <\/li>\r\n                                                        <li class=\"w-full max-w-full text-center bg-gray-100 rounded-2xl py-10 px-6 lg:px-10\">\r\n                                                                            <strong class=\"text-xl block mb-2 text-center\">Actualitzaci\u00f3 constant<\/strong>\r\n                                                                            <p class=\"mt-0 m-0 text-center mb-5\">Millorem en tecnologia i materials; el nostre objectiu \u00e9s que cada llan\u00e7ament sigui millor que l&#8217;anterior en qualitat, disseny i sostenibilitat.<\/p>\r\n                                                \r\n                    <\/li>\r\n                            <\/ul>\r\n            <\/div>\r\n\r\n<\/section>\n\n\n\r\n\r\n<section  class=\"block-text2cols\"> <!-- section -->\r\n\r\n    <div class=\"grid gap-x-baseGap md:gap-x-14 gap-y-8 lg:grid-cols-2\"> <!-- if is a full width section, apply container -->\r\n\r\n        <!-- Left column -->\r\n\r\n        <div>\r\n            <h2 class=\"mt-0 mb-3 text-balance max-w-[700px]\">Equip<\/h2>        <\/div>\r\n        \r\n        \r\n        <!-- Right column -->\r\n        <div>\r\n            <div class=\"lg:max-w-[610px] text-base\"><p>L&#8217;equip de Panots \u00e9s la nostra gran fortalesa. Est\u00e0 format per professionals de qualitat que treballen amb dedicaci\u00f3 per oferir cal\u00e7at que combini disseny, funcionalitat i sostenibilitat.<\/p>\n<p>El nostre equip multicultural inclou dissenyadors, creatius i especialistes en producci\u00f3 que treballen en sinergia per millorar cont\u00ednuament cada col\u00b7lecci\u00f3. El seu comprom\u00eds no nom\u00e9s assegura productes excepcionals, sin\u00f3 que impulsa la nostra missi\u00f3 de superar-nos en cada temporada, elevant els est\u00e0ndards de qualitat, innovaci\u00f3 i responsabilitat.<\/p>\n<\/div>        <\/div>\r\n\r\n\t<\/div>\r\n\r\n<\/section>\n\n\r\n<section  class=\"block-gallery py-8 md:py-12 lg:py-28\">\r\n\r\n    <div class=\"text-center\">\r\n\r\n        <div class=\"swiper js-gallerycarousel__slider\">\r\n                            <ul class=\"swiper-wrapper m-0 list-none items-center \">\r\n                                            <li class=\"swiper-slide\">\r\n\r\n                            <img decoding=\"async\" data-src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-gallery-3.webp\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl lazyload\" title=\"\"><noscript><img decoding=\"async\" src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-gallery-3.webp\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl\" title=\"\"><\/noscript>\r\n\r\n                        <\/li>\r\n            \r\n                                            <li class=\"swiper-slide\">\r\n\r\n                            <img decoding=\"async\" data-src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-gallery-1.webp\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl lazyload\" title=\"\"><noscript><img decoding=\"async\" src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-gallery-1.webp\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl\" title=\"\"><\/noscript>\r\n\r\n                        <\/li>\r\n            \r\n                                            <li class=\"swiper-slide\">\r\n\r\n                            <img decoding=\"async\" data-src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-gallery-2.webp\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl lazyload\" title=\"\"><noscript><img decoding=\"async\" src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-gallery-2.webp\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl\" title=\"\"><\/noscript>\r\n\r\n                        <\/li>\r\n            \r\n                                            <li class=\"swiper-slide\">\r\n\r\n                            <img decoding=\"async\" data-src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/home-new-3.webp\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl lazyload\" title=\"\"><noscript><img decoding=\"async\" src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/home-new-3.webp\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl\" title=\"\"><\/noscript>\r\n\r\n                        <\/li>\r\n            \r\n                                            <li class=\"swiper-slide\">\r\n\r\n                            <img decoding=\"async\" data-src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/home-new-2.webp\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl lazyload\" title=\"\"><noscript><img decoding=\"async\" src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/home-new-2.webp\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl\" title=\"\"><\/noscript>\r\n\r\n                        <\/li>\r\n            \r\n                                            <li class=\"swiper-slide\">\r\n\r\n                            <img decoding=\"async\" data-src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/03\/home-new-1.webp\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl lazyload\" title=\"\"><noscript><img decoding=\"async\" src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/03\/home-new-1.webp\" alt=\"\" loading=\"lazy\" width=\"\" height=\"\" data-fancybox=\"\" class=\"w-full h-full object-cover object-center aspect-landscape cursor-pointer rounded-2xl\" title=\"\"><\/noscript>\r\n\r\n                        <\/li>\r\n            \r\n                                    <\/ul>\r\n                \r\n                <div class=\"relative mt-10\">\r\n                    <div class=\"swiper-scrollbar bg-primary-50\">\r\n                        <div class=\"swiper-scrollbar-drag bg-primary\"><\/div>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                    <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\n\n\r\n<section  class=\"block-img-section pb-8 md:pb-12 lg:pb-28\">\r\n    \r\n    <div class=\"flex flex-col gap-baseGap lg:grid lg:grid-cols-2 lg:items-center \">\r\n        <div class=\"lg:max-w-[605px]\">\r\n        \r\n                            <img decoding=\"async\" data-src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia.webp\" data-srcset=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia.webp 704w, https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia-700x931.webp 700w, https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia-361x480.webp 361w, https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia-286x380.webp 286w\" width=\"704\" height=\"936\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"w-full h-full object-cover object-center rounded-2xl lazyload\" alt=\"\" sizes=\"(max-width: 704px) 100vw, 704px\" title=\"\"><noscript><img decoding=\"async\" width=\"704\" height=\"936\" src=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia.webp\" class=\"w-full h-full object-cover object-center rounded-2xl\" alt=\"\" srcset=\"https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia.webp 704w, https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia-700x931.webp 700w, https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia-361x480.webp 361w, https:\/\/panots.es\/wp-content\/uploads\/2025\/04\/about-historia-286x380.webp 286w\" sizes=\"(max-width: 704px) 100vw, 704px\" title=\"\"><\/noscript>                    \r\n            \r\n            \r\n                        \r\n            \r\n        <\/div>\r\n        <div class=\"lg:max-w-[605px]\">\r\n        \r\n                                                <h2 class=\"mb-0\">\r\n                                    Hist\u00f2ria                                    <\/h2>\r\n                                                                    <div class=\"my-5 leading-normal\">\r\n                    <p>Panots neix d&#8217;una idea senzilla per\u00f2 poderosa: crear un cal\u00e7at que no nom\u00e9s acompanyi les persones, sin\u00f3 que tamb\u00e9 expliqui hist\u00f2ries. Inspirats en les baldosas ic\u00f2niques que decoren els carrers de Barcelona, el nostre nom reflecteix la nostra connexi\u00f3 amb la comunitat, el disseny i la funcionalitat.<\/p>\n<p>Al llarg dels anys, el Panot ha estat un testimoni silenci\u00f3s de moments quotidians i extraordinaris. Des de passos afanyats en dies de pluja fins a passejades tranquil\u00b7les en una tarda assolellada, aquestes rajoles han presenciat el vaiv\u00e9 de la vida, convertint-se en un s\u00edmbol de la hist\u00f2ria, la cultura i la humanitat compartida.<\/p>\n<p>Amb aquest esperit, a Panots dissenyem sabates que encarnen la mateixa ess\u00e8ncia: duradores, aut\u00e8ntiques i plenes de significat. El nostre equip de dissenyadors, procedents de quatre continents, treballa conjuntament per fusionar influ\u00e8ncies globals en col\u00b7leccions que combinen estil, funcionalitat i una connexi\u00f3 profunda amb l&#8217;entorn.<\/p>\n<p>Des de 2023, hem fet un pas m\u00e9s cap a la nostra missi\u00f3: treballar perqu\u00e8 les comunitats necessitades a Vene\u00e7uela puguin beneficiar-se d&#8217;iniciatives com la nostra campanya RENUEVA, que promou el reciclatge i la reutilitzaci\u00f3 de cal\u00e7at.<\/p>\n<p>A Panots, la nostra missi\u00f3 \u00e9s crear un moviment que transcendeixi fronteres, promovent un canvi global. Volem que cada persona que porti Panots sigui part d\u2019aquesta visi\u00f3, contribuint de manera directa o indirecta al benestar del medi ambient i al suport de les comunitats que ho necessiten.<\/p>\n<p>Volem expandir-nos arreu del m\u00f3n, no nom\u00e9s per portar cal\u00e7at amb hist\u00f2ries, sin\u00f3 per crear oportunitats d&#8217;ajuda a cada rac\u00f3 possible. La nostra missi\u00f3 no \u00e9s nom\u00e9s que visquis moments inoblidables portant els teus Panots, sin\u00f3 que un dia puguis donar-los una segona vida, entregant-los a alg\u00fa que els necessiti, perqu\u00e8 aquesta persona tamb\u00e9 pugui explicar les seves pr\u00f2pies hist\u00f2ries.<\/p>\n<p><strong>I \u00e9s que on hi ha Panots, sempre hi haur\u00e0 una hist\u00f2ria a explicar.<\/strong><\/p>\n                <\/div>\r\n                                <\/div>\r\n    <\/div>\r\n\r\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5230","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/panots.es\/ca\/wp-json\/wp\/v2\/pages\/5230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/panots.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/panots.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/panots.es\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/panots.es\/ca\/wp-json\/wp\/v2\/comments?post=5230"}],"version-history":[{"count":0,"href":"https:\/\/panots.es\/ca\/wp-json\/wp\/v2\/pages\/5230\/revisions"}],"wp:attachment":[{"href":"https:\/\/panots.es\/ca\/wp-json\/wp\/v2\/media?parent=5230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}